{"id":258,"date":"2019-10-17T15:22:04","date_gmt":"2019-10-17T14:22:04","guid":{"rendered":"https:\/\/mythslegendes.com\/?page_id=258"},"modified":"2022-12-03T22:06:50","modified_gmt":"2022-12-03T22:06:50","slug":"la-submersion-de-la-ville-dys","status":"publish","type":"page","link":"https:\/\/mythslegendes.com\/es\/mitologia-bretona\/la-inmersion-de-la-ciudad-dys\/","title":{"rendered":"La inundaci\u00f3n de la ciudad de Ys"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"258\" class=\"elementor elementor-258\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-abbaeef elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"abbaeef\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-5cdf433\" data-id=\"5cdf433\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-8f44e9a elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"8f44e9a\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/mythslegendes.com\/es\/mitologia-bretona\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mitolog\u00eda bretona<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-8e59f18\" data-id=\"8e59f18\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-bd1764c elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"bd1764c\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Mythologie_bretonne\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Wiki<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-7e3113db elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"7e3113db\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-34fcf46\" data-id=\"34fcf46\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-3f8b8f2e elementor-widget elementor-widget-text-editor\" data-id=\"3f8b8f2e\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t\n<p class=\"wp-block-paragraph\">Aqu\u00ed est\u00e1n los diferentes <a href=\"https:\/\/mythslegendes.com\/es\/bibliotecas-de-libros\/\">libros<\/a> de la <a href=\"https:\/\/mythslegendes.com\/es\/\">leyenda<\/a> de la ciudad de Ys y su sumergimiento.<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-5284 size-full\" src=\"https:\/\/mythslegendes.com\/wp-content\/uploads\/2020\/09\/AlphaOmega-e1602613368367.png\" alt=\"la ciudad Ys y su inmersi\u00f3n\" width=\"25\" height=\"26\" title=\"\"><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenido<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Palanca<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/mythslegendes.com\/es\/mitologia-bretona\/la-inmersion-de-la-ciudad-dys\/#La-ville-dYs-et-sa-submersion\" >La ciudad de Ys y su inmersi\u00f3n<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"La-ville-dYs-et-sa-submersion\"><\/span>La ciudad de Ys y su inmersi\u00f3n<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>I<\/p>\n\n<p class=\"has-text-align-justify wp-block-paragraph\">\u00bfO\u00edste, o\u00edste lo que el hombre de Dios le dijo al rey Gradlon que est\u00e1 en <a href=\"https:\/\/mythslegendes.com\/es\/mitologia-bretona\/\">Ys<\/a> ?<br \/>\u00a0\u00bb No te entregues al amor; no te entregues a la locura. \u00a1Despu\u00e9s del placer, el dolor!<br \/>\u00a0\u201cEl que muerde la carne del pez, ser\u00e1 mordido por el pez; y el que traga, ser\u00e1 tragado.<br \/>\u00a0Y el que bebe y mezcla vino, beber\u00e1 agua como un pez; y quien no sabe, aprender\u00e1. &quot;\u00a0<\/p>\n\n<p class=\"wp-block-paragraph\">II<\/p>\n\n<p class=\"has-text-align-justify wp-block-paragraph\">El rey Gradlon habl\u00f3: - Felices invitados, quiero ir a dormir un poco.<br \/>\u2013 Dormir\u00e1s ma\u00f1ana por la ma\u00f1ana; qu\u00e9date con nosotros esta noche; sin embargo, que se haga como quieres.<br \/>En esto, el amante suavemente, muy suavemente, estas palabras fluyeron al o\u00eddo de la hija del rey:<br \/>&quot;Dulce Dahut, \u00bfy la llave?&quot;<br \/>\u2013 Se quitar\u00e1 la llave; el pozo se abrir\u00e1: \u00a1que se haga seg\u00fan vuestros deseos!<\/p>\n\n<p class=\"wp-block-paragraph\">III<\/p>\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Ahora bien, cualquiera que hubiera visto dormir al anciano rey, habr\u00eda sido presa de la admiraci\u00f3n,<br \/>de admiraci\u00f3n al verlo con su manto p\u00farpura,<br \/>su cabello blanco como la nieve flotando sobre sus hombros, y su cadena dorada alrededor de su cuello.<br \/>Cualquiera que hubiera estado atento habr\u00eda visto a la chica blanca entrar en la habitaci\u00f3n sin hacer ruido, descalza:<br \/>Se acerc\u00f3 al rey su padre, se arrodill\u00f3 y le quit\u00f3 la cadena y la llave.<\/p>\n\n<p class=\"wp-block-paragraph\">IV<\/p>\n\n<p class=\"has-text-align-justify wp-block-paragraph\">Siempre duerme, duerme el rey. Pero un grito sube en la llanura: \u2013 \u00a1El agua se suelta! la ciudad est\u00e1 sumergida!<br \/>\u201c\u00a1Se\u00f1or Rey, lev\u00e1ntate! \u00a1y a caballo! y lejos de aqu\u00ed! el mar desbordado rompe sus diques!<br \/>\u00a1Maldita sea la doncella blanca que abri\u00f3, despu\u00e9s de la fiesta, la puerta del pozo de la ciudad de Ys, esa barrera del mar!<\/p>\n\n<p class=\"wp-block-paragraph\">V<\/p>\n\n<p class=\"has-text-align-justify wp-block-paragraph\">\u2013 Guardabosques, guardabosques, dime, el caballo salvaje de Gradlon, \u00bflo has visto pasar por este valle?<br \/>\u2013 No vi pasar el caballo de Gradlon por aqu\u00ed, solo lo escuch\u00e9 en la noche oscura:<br \/>Trip, trep, trip, trep, trip trep, \u00a1r\u00e1pido como el fuego!<br \/>\u201c\u00bfHas visto, pescador, a la hija del mar, peinarse rubia como el oro, al sol del mediod\u00eda, a la orilla del agua?<br \/>\u2013 Vi a la ni\u00f1a blanca del mar, hasta la escuch\u00e9 gorjear: sus cantos eran quejumbrosos como las olas.<\/p>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Mythologie Bretonne Wiki Voici les diff\u00e9rents livres de la l\u00e9gende de la ville d&rsquo;Ys et sa submersion. La ville d&rsquo;Ys &hellip; <\/p>","protected":false},"author":1,"featured_media":21,"parent":96,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-258","page","type-page","status-publish","has-post-thumbnail","hentry"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/mythslegendes.com\/es\/wp-json\/wp\/v2\/pages\/258","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mythslegendes.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mythslegendes.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mythslegendes.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mythslegendes.com\/es\/wp-json\/wp\/v2\/comments?post=258"}],"version-history":[{"count":1,"href":"https:\/\/mythslegendes.com\/es\/wp-json\/wp\/v2\/pages\/258\/revisions"}],"predecessor-version":[{"id":24483,"href":"https:\/\/mythslegendes.com\/es\/wp-json\/wp\/v2\/pages\/258\/revisions\/24483"}],"up":[{"embeddable":true,"href":"https:\/\/mythslegendes.com\/es\/wp-json\/wp\/v2\/pages\/96"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/mythslegendes.com\/es\/wp-json\/wp\/v2\/media\/21"}],"wp:attachment":[{"href":"https:\/\/mythslegendes.com\/es\/wp-json\/wp\/v2\/media?parent=258"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}