{"id":613,"date":"2020-06-15T09:54:28","date_gmt":"2020-06-15T08:54:28","guid":{"rendered":"https:\/\/mythslegendes.com\/?page_id=613"},"modified":"2022-12-03T22:06:56","modified_gmt":"2022-12-03T22:06:56","slug":"la-princesse-de-tronkolaine","status":"publish","type":"page","link":"https:\/\/mythslegendes.com\/es\/mitologia-bretona\/la-princesa-de-tronkolaine\/","title":{"rendered":"La princesa de Tronkolaine"},"content":{"rendered":"<div data-elementor-type=\"wp-page\" data-elementor-id=\"613\" class=\"elementor elementor-613\">\n\t\t\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-67bf70b elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"67bf70b\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-f99fd76\" data-id=\"f99fd76\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-10492df elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"10492df\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/mythslegendes.com\/es\/mitologia-bretona\/\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Mitolog\u00eda bretona<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t<div class=\"elementor-column elementor-col-50 elementor-top-column elementor-element elementor-element-404fa16\" data-id=\"404fa16\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-c3effa8 elementor-align-justify elementor-widget elementor-widget-button\" data-id=\"c3effa8\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"button.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<div class=\"elementor-button-wrapper\">\n\t\t\t\t\t<a class=\"elementor-button elementor-button-link elementor-size-sm\" href=\"https:\/\/fr.wikipedia.org\/wiki\/Mythologie_bretonne\" target=\"_blank\" rel=\"noopener\">\n\t\t\t\t\t\t<span class=\"elementor-button-content-wrapper\">\n\t\t\t\t\t\t\t\t\t<span class=\"elementor-button-text\">Wiki<\/span>\n\t\t\t\t\t<\/span>\n\t\t\t\t\t<\/a>\n\t\t\t\t<\/div>\n\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<section class=\"elementor-section elementor-top-section elementor-element elementor-element-6f9a90d2 elementor-section-boxed elementor-section-height-default elementor-section-height-default\" data-id=\"6f9a90d2\" data-element_type=\"section\" data-e-type=\"section\">\n\t\t\t\t\t\t<div class=\"elementor-container elementor-column-gap-default\">\n\t\t\t\t\t<div class=\"elementor-column elementor-col-100 elementor-top-column elementor-element elementor-element-c82becd\" data-id=\"c82becd\" data-element_type=\"column\" data-e-type=\"column\">\n\t\t\t<div class=\"elementor-widget-wrap elementor-element-populated\">\n\t\t\t\t\t\t<div class=\"elementor-element elementor-element-7582856b elementor-widget elementor-widget-text-editor\" data-id=\"7582856b\" data-element_type=\"widget\" data-e-type=\"widget\" data-widget_type=\"text-editor.default\">\n\t\t\t\t<div class=\"elementor-widget-container\">\n\t\t\t\t\t\t\t\t\t<p><\/p>\n<p class=\"wp-block-paragraph\">Aqu\u00ed est\u00e1 la historia de la Princesa de Tronkolaine. Hab\u00eda una vez un viejo carbonero al que se le hab\u00edan realizado veinticinco bautismos. Ya no pod\u00eda encontrar un padrino para el vig\u00e9simo sexto hijo que acababa de nacer de \u00e9l. Encontr\u00f3 una madrina.<\/p>\n<p><img decoding=\"async\" class=\"alignnone wp-image-5284 size-full\" src=\"https:\/\/mythslegendes.com\/wp-content\/uploads\/2020\/09\/AlphaOmega-e1602613368367.png\" alt=\"la princesa de Tronkolaine\" width=\"25\" height=\"26\" title=\"\"><\/p>\n<div id=\"ez-toc-container\" class=\"ez-toc-v2_0_87 counter-hierarchy ez-toc-counter ez-toc-grey ez-toc-container-direction\">\n<div class=\"ez-toc-title-container\">\n<p class=\"ez-toc-title\" style=\"cursor:inherit\">Contenido<\/p>\n<span class=\"ez-toc-title-toggle\"><a href=\"#\" class=\"ez-toc-pull-right ez-toc-btn ez-toc-btn-xs ez-toc-btn-default ez-toc-toggle\" aria-label=\"Alternar tabla de contenidos\"><span class=\"ez-toc-js-icon-con\"><span class=\"\"><span class=\"eztoc-hide\" style=\"display:none;\">Palanca<\/span><span class=\"ez-toc-icon-toggle-span\"><svg style=\"fill: #999;color:#999\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" class=\"list-377408\" width=\"20px\" height=\"20px\" viewbox=\"0 0 24 24\" fill=\"none\"><path d=\"M6 6H4v2h2V6zm14 0H8v2h12V6zM4 11h2v2H4v-2zm16 0H8v2h12v-2zM4 16h2v2H4v-2zm16 0H8v2h12v-2z\" fill=\"currentColor\"><\/path><\/svg><svg style=\"fill: #999;color:#999\" class=\"arrow-unsorted-368013\" xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"10px\" height=\"10px\" viewbox=\"0 0 24 24\" version=\"1.2\" baseprofile=\"tiny\"><path d=\"M18.2 9.3l-6.2-6.3-6.2 6.3c-.2.2-.3.4-.3.7s.1.5.3.7c.2.2.4.3.7.3h11c.3 0 .5-.1.7-.3.2-.2.3-.5.3-.7s-.1-.5-.3-.7zM5.8 14.7l6.2 6.3 6.2-6.3c.2-.2.3-.5.3-.7s-.1-.5-.3-.7c-.2-.2-.4-.3-.7-.3h-11c-.3 0-.5.1-.7.3-.2.2-.3.5-.3.7s.1.5.3.7z\"\/><\/svg><\/span><\/span><\/span><\/a><\/span><\/div>\n<nav><ul class='ez-toc-list ez-toc-list-level-1' ><li class='ez-toc-page-1 ez-toc-heading-level-2'><a class=\"ez-toc-link ez-toc-heading-1\" href=\"https:\/\/mythslegendes.com\/es\/mitologia-bretona\/la-princesa-de-tronkolaine\/#La-princesse-de-Tronkolaine\" >La princesa de Tronkolaine<\/a><\/li><\/ul><\/nav><\/div>\n<h2><span class=\"ez-toc-section\" id=\"La-princesse-de-Tronkolaine\"><\/span>La princesa de Tronkolaine<span class=\"ez-toc-section-end\"><\/span><\/h2>\n<p>Mientras iba en busca de un padrino, se encontr\u00f3 con un hermoso carruaje, en el que hab\u00eda un rey. Se arrodill\u00f3 en el camino, sombrero en mano. El rey, al verlo, sali\u00f3 de su carruaje y le dio una moneda de dos coronas.<\/p>\n<p>\u2014Excepto su excelencia, se\u00f1or \u2014dijo el carbonero\u2014, no estoy buscando limosna, sino un padrino para mi \u00faltimo hijo, que acaba de nacer, y no encuentro ninguno.<br \/>- \u00bfPorqu\u00e9 entonces? pregunt\u00f3 el rey.<br \/>- Es porque, se\u00f1or, ya he tenido veinticinco bautismos, y todos mis vecinos han sido amigos m\u00edos. Encuentro una madrina.<br \/>- Y bien ! respondi\u00f3 el rey, vuelve a casa; ven a la iglesia con el ni\u00f1o y la madrina, y yo ser\u00e9 el padrino.<\/p>\n<p>Y el viejo carbonero regres\u00f3 a su choza, bastante feliz. Se lo dijo a la madrina, y fueron a la iglesia con el ni\u00f1o. El rey ya los estaba esperando.<\/p>\n<p>Cuando termin\u00f3 el bautismo, el padrino le dio mil coronas al padre para que criara a su ahijado y lo enviara a la escuela. Le dio otra mitad de platino para que se la diera al ni\u00f1o, quien se la devolver\u00eda cuando tuviera dieciocho a\u00f1os. Luego se fue.<\/p>\n<p>El ni\u00f1o se llamaba Charles.<\/p>\n<p>Cuando ten\u00eda siete u ocho a\u00f1os, Charles fue enviado a la escuela y estaba aprendiendo todo lo que quer\u00eda. Cuando ten\u00eda dieciocho a\u00f1os, su padre le dio la mitad del platino y le dijo que fuera a ver a su padrino, el rey de Francia, a su corte de Par\u00eds. El joven parti\u00f3 montado en un hermoso caballo y con su mitad platino en el bolsillo. Se ve\u00eda realmente bien. I<\/p>\n<p>Encontr\u00f3, en un camino hueco y estrecho, a una viejecita, quien le dijo que un poco m\u00e1s adelante ver\u00eda, cerca de una fuente, un individuo que lo invitar\u00eda a beber; - &quot;pero, sigue tu camino, hijo m\u00edo, y no bebas, cualquier insistencia que ponga ah\u00ed&quot;. &quot;<\/p>\n<p>&quot;Est\u00e1 bien, abuela, no beber\u00e9 el agua de la fuente&quot;, dijo Charles.<br \/>Al llegar a la fuente, vio al individuo sentado a la sombra, como un viajero que est\u00e1 descansando un momento, y le dijo:<br \/>- Joven, ven y bebe un poco de agua.<br \/>- Gracias ! No tengo sed, respondi\u00f3.<\/p>\n<p>- Ven y bebe solo una gota, nunca hab\u00edas bebido tan buena agua.<br \/>Insisti\u00f3 tanto que se acerc\u00f3 a saborear el agua de la fuente. Pero, arrodill\u00e1ndose para beber la palangana, el extra\u00f1o sac\u00f3 su mitad de platino del bolsillo, salt\u00f3 sobre su caballo y parti\u00f3 al galope. Charles corri\u00f3 tras \u00e9l; pero desafortunadamente ! no pudo alcanzarlo y pronto perdi\u00f3 de vista al hombre y al caballo.<br \/>- \u00a1Pobre de m\u00ed! se dijo a s\u00ed mismo, no obedec\u00ed el consejo de la anciana. Que hacer ahora ? Cualquier cosa ! Ir\u00e9 a pie; Tarde o temprano tambi\u00e9n llegar\u00e9 a Par\u00eds, y luego ya veremos.<\/p>\n<p>Y parti\u00f3 de nuevo.<\/p>\n<p>Cuando el hombre de la fuente, el ladr\u00f3n, lleg\u00f3 a Par\u00eds, inmediatamente pidi\u00f3 hablar con el rey y le present\u00f3 su mitad de platino. Las dos mitades se juntaron y se encontr\u00f3 que se parec\u00edan entre s\u00ed y encajaban perfectamente; Tanto es as\u00ed que el sinverg\u00fcenza fue bienvenido por el rey, quien lo tom\u00f3 por su ahijado, y no ten\u00eda nada que hacer todos los d\u00edas m\u00e1s que comer, beber, comer bien y salir a caminar.<\/p>\n<p>Alg\u00fan tiempo despu\u00e9s, tambi\u00e9n lleg\u00f3 Charles. Fue llevado al palacio como pastor. El falso ahijado, al ver esto, tuvo miedo y busc\u00f3 los medios para deshacerse de \u00e9l y perderlo. Un d\u00eda le dijo al rey:<br \/>- Si supieras, padrino, \u00bfqu\u00e9 dijo el pastor?<br \/>- Que dijo el ? pregunt\u00f3 el rey.<\/p>\n<p>- Lo que dijo ? Dijo que \u00e9l era el hombre para ir y preguntarle al Sol por qu\u00e9 est\u00e1 tan rojo por la ma\u00f1ana cuando sale.<br \/>- \u00a1Bah! no es posible, a menos que haya perdido la cabeza.<br \/>- \u00c9l lo dijo, en mi fe, mi padrino, y creo que ser\u00eda bueno enviarlo all\u00ed.<br \/>El pastor fue llamado al rey.<br \/>- \u00bfC\u00f3mo? &#039;O&#039; \u00a1Qu\u00e9! joven pastor, dijiste que eres el hombre para ir y preguntarle al sol por qu\u00e9 est\u00e1 tan rojo cuando sale por la ma\u00f1ana.<\/p>\n<p>- \u00bfYo, mi rey? \u00bfC\u00f3mo pude haber dicho tal cosa?<br \/>- Lo dijiste, porque mi ahijado me asegur\u00f3; tienes que lograr aquello de lo que te jactaste, de lo contrario, solo existe la muerte para ti. Te marchar\u00e1s ma\u00f1ana por la ma\u00f1ana.<\/p>\n<p>Ah\u00ed est\u00e1 el pobre Charles muy avergonzado, le ruego que lo crea. No durmi\u00f3 ni una gota en toda la noche.<\/p>\n<p>A la ma\u00f1ana siguiente, antes de partir, hizo la se\u00f1al de la cruz y dijo: \u201c\u00a1Por la gracia de Dios! &quot;<\/p>\n<p>Camin\u00f3 hacia el este. A\u00fan no hab\u00eda ido muy lejos cuando conoci\u00f3 a un anciano de barba blanca, que le dijo:<br \/>- \u00bfA d\u00f3nde vas as\u00ed, hijo m\u00edo, y por qu\u00e9 est\u00e1s tan triste?<br \/>- Bueno, abuelo, a d\u00f3nde voy, apenas lo s\u00e9; y, si estoy triste, no es sin raz\u00f3n. El rey me orden\u00f3 que fuera a preguntarle al sol por qu\u00e9 est\u00e1 tan rojo cuando sale por la ma\u00f1ana.<\/p>\n<p>- Y bien ! muchacho, haz exactamente lo que te digo y podr\u00e1s tener \u00e9xito. Aqu\u00ed hay un caballo de madera; s\u00fabete a \u00e9l y te llevar\u00e1 a la tierra donde sale el sol. Llegar\u00e1s al pie de una monta\u00f1a muy alta; luego descender\u00e1s, dejar\u00e1s tu caballo al pie de la monta\u00f1a y subir\u00e1s a la cima. All\u00ed ver\u00e1 un hermoso castillo. Es el castillo del sol. Solo tendr\u00e1s que entrar y hacer tu comisi\u00f3n.<br \/>- Gracias, abuelo.<\/p>\n<p>Charles mont\u00f3 en el caballo de madera, que se elev\u00f3 con \u00e9l en el aire y pronto se encontraron al pie de la alta monta\u00f1a. Charles lo subi\u00f3 solo hasta la cima. Luego vio el Palacio del Sol, entr\u00f3 sin obst\u00e1culos y pregunt\u00f3:<br \/>- \u00bfEst\u00e1 el sol en casa?<br \/>- No, respondi\u00f3 una anciana, que estaba all\u00ed, - su madre, sin duda; - \u00bfQu\u00e9 quieres de \u00e9l?<br \/>- Necesito hablar con ella, abuela.<\/p>\n<p>- Y bien ! si quieres esperar un poco, llegar\u00e1 sin demora. Pero mi pobre hijo, mi hijo tendr\u00e1 mucha hambre cuando llegue y querr\u00e1 comerte. Qu\u00e9date igual, que tu mirada me agrada y evitar\u00e9 que te haga da\u00f1o.<br \/>Poco despu\u00e9s de que llegara el sol, gritando:<br \/>- Tengo hambre ! \u00a1Estoy muy hambriento! mi madre.<br \/>&quot;Que bueno, si\u00e9ntate ah\u00ed, hijo m\u00edo, y te dar\u00e9 de comer&quot;, le dijo la anciana.<\/p>\n<p>- \u00a1Huelo a Christian, mam\u00e1, y debo com\u00e9rmelo! grit\u00f3 el sol, un momento despu\u00e9s.<br \/>- Y bien ! por ejemplo, si crees que te voy a dejar comer a este ni\u00f1o, \u00a1est\u00e1s muy equivocado! \u00a1Mira qu\u00e9 chico tan encantador!<br \/>- \u00bfQu\u00e9 viniste a hacer aqu\u00ed? pregunt\u00f3 el Sol a Charles.<br \/>- Me han ordenado, monse\u00f1or el Sol, que vaya a preguntarle por qu\u00e9 est\u00e1 tan colorado por la ma\u00f1ana cuando se levanta.<\/p>\n<p>- Y bien ! No te har\u00e9 da\u00f1o, porque me gusta tu look, y hasta te ense\u00f1ar\u00e9 lo que quieres saber. All\u00ed vive la Princesa de Tronkolaine, en un castillo contiguo al m\u00edo, y todas las ma\u00f1anas tengo que mostrarme en todo mi esplendor, cuando paso por su casa, para no ser derrotado por ella en belleza.<\/p>\n<p>Al d\u00eda siguiente, el Sol sali\u00f3 temprano en la ma\u00f1ana y comenz\u00f3 su recorrido, como de costumbre, y Charles se fue tan pronto como lo hizo. Al bajar de la monta\u00f1a, se encontr\u00f3 con su caballo de madera esper\u00e1ndolo. Se subi\u00f3 a \u00e9l y fue devuelto en poco tiempo al lugar donde hab\u00eda conocido al anciano. Todav\u00eda estaba all\u00ed esper\u00e1ndola.<\/p>\n<p>- Y bien ! hijo m\u00edo, le dijo, \u00bfhas tenido \u00e9xito en tu negocio?<br \/>- S\u00ed, de verdad, abuelo, respondi\u00f3 Charles, \u00a1y la bendici\u00f3n de Dios sea contigo!<br \/>- Est\u00e1 bien ; cuando me necesites de nuevo, ll\u00e1mame y me volver\u00e1s a ver.<\/p>\n<p>E inmediatamente desapareci\u00f3, no supo c\u00f3mo.<br \/>Cuando Carlos regres\u00f3 al palacio del rey, todos se sorprendieron de lo feliz y alegre que estaba.<\/p>\n<p>- Y bien ! le dijo el rey, \u00bfme dir\u00e1s ahora por qu\u00e9 el sol est\u00e1 tan rojo por la ma\u00f1ana cuando sale?<br \/>- S\u00ed, se\u00f1or, se lo dir\u00e9.<br \/>- Porqu\u00e9 entonces ?<br \/>- Esto se debe a que, no muy lejos del castillo del Sol, est\u00e1 el de la Princesa de Tronkolaine, y debe aparecer, cada ma\u00f1ana, en todo su esplendor, cuando pase por encima del castillo, para no ser eclipsado por \u00e9l. .<\/p>\n<p>&quot;Eso es bueno&quot;, respondi\u00f3 el rey. Y lo envi\u00f3 de regreso a sus ovejas.<br \/>Poco despu\u00e9s, el falso ahijado volvi\u00f3 a decirle al rey:<br \/>- Si supieras, padrino, \u00bfqu\u00e9 dijo el pastor de ovejas?<br \/>- \u00bfY qu\u00e9 volvi\u00f3 a decir?<br \/>- Lo que dijo ? Dijo que es el hombre que traer\u00e1 a la princesa de Tronkolaine aqu\u00ed para que se case con ella.<br \/>- Verdaderamente ? Dile que venga a buscarme ahora.<\/p>\n<p>El pobre Carlos se acerc\u00f3 al rey, muy inquieto.<br \/>- \u00bfC\u00f3mo? &#039;O&#039; \u00a1Qu\u00e9! joven pastor, \u00bfdijiste que podr\u00edas traerme aqu\u00ed a la princesa de Tronkolaine, para que sea mi esposa?<br \/>- \u00bfC\u00f3mo pude haber dicho tal cosa, se\u00f1or? Tendr\u00eda que haber perdido completamente la cabeza para hablar as\u00ed.<br \/>- Te jactaste de eso, y tienes que hacerlo, de lo contrario solo hay muerte para ti.<\/p>\n<p>A la ma\u00f1ana siguiente, Charles parti\u00f3 de nuevo, triste y preocupado. &quot;Si todav\u00eda me encuentro con el anciano del otro<br \/>hora ! Se dijo a s\u00ed mismo. Apenas hab\u00eda dicho estas palabras cuando vio que el anciano se le acercaba.<br \/>- Hola, hijo m\u00edo, le dijo.<br \/>- Para ti tambi\u00e9n, abuelo.<br \/>- \u00bfA d\u00f3nde vas as\u00ed, hijo m\u00edo?<\/p>\n<p>- Bueno, abuelo, realmente no lo s\u00e9. El rey volvi\u00f3 a ordenarme que trajera a la princesa de Tronkolaine a su corte, y no s\u00e9 c\u00f3mo hacerlo.<br \/>- Eso est\u00e1 bien, muchacho. Toma esta varita blanca primero. Vuelve con el rey y dile que necesitas tres botes, uno cargado de avena, otro con tocino y el tercero con carne salada. La papilla ser\u00e1 para el rey hormiga, a quien encontrar\u00e1s en una isla en medio del mar, cuando llegues a esta isla preguntar\u00e1s: - &quot;\u00bfNo es aqu\u00ed donde habita el rey hormiga?&quot; - S\u00ed, se le dir\u00e1.<\/p>\n<p>&quot;Bueno, aqu\u00ed tengo un regalo para \u00e9l&quot;, agregar\u00e1, se\u00f1alando el bote cargado de avena. Entonces, llegar\u00e1n todas las hormigas de la isla, y en un instante, vaciar\u00e1n el bote.<br \/>- &quot;\u00a1Mi bendici\u00f3n sea contigo!&quot; El rey de las hormigas entonces te dir\u00e1, y si alguna vez nos necesitas, llama al rey de las hormigas, y \u00e9l vendr\u00e1 de inmediato. - M\u00e1s adelante, encontrar\u00e1s otra isla, donde reside el rey le\u00f3n. Volver\u00e1s a preguntar, cuando llegues: - &quot;\u00bfNo es aqu\u00ed donde habita el Rey de los Leones?&quot; - S\u00ed, te responder\u00e1n, est\u00e1 aqu\u00ed. &quot;<\/p>\n<p>Y agregar\u00e1s: - \u201cEs porque aqu\u00ed hay un regalo que tengo para \u00e9l; - y mostrar\u00e1s el barco cargado de tocino. Entonces ver\u00e1s leones viniendo de todos los lados de la isla, y en un instante el bote se vaciar\u00e1. El Rey de los Leones tambi\u00e9n te dir\u00e1: - &quot;\u00a1Mi bendici\u00f3n sea contigo!&quot; Si alguna vez me necesitas, simplemente llama al Rey de los Leones y estar\u00e9 all\u00ed. \u00bb- Finalmente, llegar\u00e1s a una tercera isla, donde vive el rey de los halcones. A medida que te acerques, preguntar\u00e1s:<\/p>\n<p>- &quot;\u00bfNo es aqu\u00ed donde habita el rey de los halcones?&quot; - S\u00ed, te responder\u00e1n, est\u00e1 aqu\u00ed. - Es bueno, agregar\u00e1s, aqu\u00ed tienes un regalo que tengo para \u00e9l. - Y mostrar\u00e1s el barco cargado de carne salada. Inmediatamente llegar\u00e1 el rey de los halcones, acompa\u00f1ado de sus s\u00fabditos, y en un instante se vaciar\u00e1 la barca. - &quot;\u00a1Mi bendici\u00f3n sea contigo!&quot; el rey de los halcones dir\u00e1 tambi\u00e9n, y si alguna vez me necesitas, todo lo que tienes que hacer es llamar al rey de los halcones, y yo ir\u00e9 enseguida. &quot;<\/p>\n<p>- El rey, tu padrino, te proporcionar\u00e1 los tres botes cargados de papilla, tocino y carne. Antes de embarcar, haz una cruz con tu varita blanca sobre la arena de la orilla, e inmediatamente soplar\u00e1 un viento favorable que te llevar\u00e1 a tu destino. Tenga cuidado de hacer todo exactamente como le dije y tendr\u00e1 \u00e9xito.<\/p>\n<p>&quot;Gracias, y mis bendiciones sean contigo, abuelo&quot;, dijo Charles.<\/p>\n<p>Y se fue.<\/p>\n<p>Aqu\u00ed est\u00e1 Charles en el mar, con sus tres barcos. Llega a la primera isla, donde vive Ant King, y pregunta:<br \/>- \u00bfNo es aqu\u00ed donde habita el Rey Hormiga?<br \/>- S\u00ed, est\u00e1 aqu\u00ed, respondemos.<br \/>- Bueno, aqu\u00ed tengo un regalo para \u00e9l; ve y dile, te lo ruego, que venga a recibirlo.<\/p>\n<p>El rey de las hormigas fue advertido, y de inmediato lleg\u00f3 acompa\u00f1ado de una infinidad de hormigas.<\/p>\n<p>En un instante la barca se vaci\u00f3 y el rey dijo:<br \/>- Mi bendici\u00f3n para ti, Carlos, ahijado del rey de Francia. T\u00fa nos salvaste; porque mi reino fue asolado por el hambre, y todos est\u00e1bamos a punto de morir de hambre. Si alguna vez nos necesita a m\u00ed y a mis s\u00fabditos, simplemente llame al Rey de las Hormigas y estar\u00e9 all\u00ed.<\/p>\n<p>Carlos prosigui\u00f3 su viaje y, para abreviar, lleg\u00f3 a la isla donde viv\u00eda el rey de los leones, luego a la que habitaba el rey de los halcones; Hizo exactamente lo que el anciano le hab\u00eda recomendado, y todos le prometieron ayuda y protecci\u00f3n, si era necesario. Antes de salir de la Isla de los Halcones, le pregunt\u00f3 a su rey:<\/p>\n<p>- \u00bfEstoy todav\u00eda lejos del palacio de la Princesa de Tronkolaine?<br \/>&quot;A\u00fan te queda un largo camino por recorrer&quot;, respondieron; pero llegar\u00e1s sin dificultad. Cuando llegues, ver\u00e1s a la princesa junto a una fuente, ocupada peinando su cabello rubio, con un peine dorado y un peine de marfil. Ten cuidado de no ser visto de ella, antes de verla, porque te encantar\u00e1.<\/p>\n<p>\u00a0Ella estar\u00e1 debajo de un naranjo, que est\u00e1 sobre la fuente. Ve despacio, despacio, sube al \u00e1rbol, coge una naranja y t\u00edrala r\u00e1pidamente a la fuente. Entonces. Princess levantar\u00e1 la cabeza, te sonreir\u00e1 y luego te invitar\u00e1 a bajar y acompa\u00f1arla a su castillo. Puedes seguirla sin miedo.<\/p>\n<p>- Gracias, dijo Carlos al rey de los halcones. Y continu\u00f3 su camino.<br \/>Lleg\u00f3 sin demora al pie del castillo, un castillo magn\u00edfico. Vio a la princesa junto a la fuente, ocupada peinando su cabello rubio con un peine dorado y un peine de marfil, bajo un naranjo; se trep\u00f3 al \u00e1rbol, sin ser visto por ella, cogi\u00f3 una naranja y la arroj\u00f3 a la palangana de la fuente. La princesa inmediatamente levant\u00f3 la cabeza y, al ver a Charles en el \u00e1rbol:<\/p>\n<p>- \u00a1Ah! ella dijo: Carlos, ahijado del rey de Francia, \u00a1as\u00ed que eres t\u00fa quien est\u00e1 all\u00ed! Se bienvenido. Baja las escaleras y acomp\u00e1\u00f1ame a mi castillo. No quiero hacerte da\u00f1o; de lo contrario.<br \/>Charles la sigui\u00f3 hasta su castillo. Nunca sus ojos hab\u00edan visto algo tan hermoso.<\/p>\n<p><\/p>\n<p class=\"wp-block-paragraph\">Llevaba all\u00ed quince d\u00edas, en medio de todo tipo de placeres, cuando le pregunt\u00f3 un d\u00eda a la princesa si consentir\u00eda en acompa\u00f1arlo al palacio del rey de Francia.<br \/>&quot;Con mucho gusto&quot;, respondi\u00f3 ella, &quot;si logras tres trabajos que te asignar\u00e9&quot;.<br \/>&quot;Siempre lo intentar\u00e9&quot;, dijo.<\/p>\n<p>A la ma\u00f1ana siguiente, la Princesa lo llev\u00f3 a un \u00e1tico, frente a un gran mont\u00f3n de semillas de todo tipo. Hab\u00eda semillas de lino, tr\u00e9bol, c\u00e1\u00f1amo, nabo y repollo, mezclados. Ella le dijo que antes de la puesta del sol ten\u00eda que haber reunido todas las semillas del mismo tipo en un mont\u00f3n, sin que hubiera una semilla de diferente naturaleza en ninguno de los montones. Entonces ella se fue.<\/p>\n<p>El pobre Charles, al quedarse solo, se ech\u00f3 a llorar, porque no cre\u00eda que fuera posible que nadie en el mundo pudiera realizar semejante obra. Luego record\u00f3 al Rey Hormiga. Me hab\u00eda dicho, se dijo a s\u00ed mismo, que si alguna vez lo necesitaba a \u00e9l ya su gente, tendr\u00eda que llamarlos y ellos vendr\u00edan en mi ayuda. Me parece que los necesito lo suficiente en este momento. As\u00ed que veamos si estaba diciendo la verdad:<\/p>\n<p>- \u00a1Rey hormiga, ven en mi ayuda, porque realmente lo necesito!<br \/>E inmediatamente lleg\u00f3 el Rey de las Hormigas.<br \/>- \u00bfQu\u00e9 hay para tu servicio, pregunt\u00f3, Carlos, ahijado del rey de Francia?<br \/>Charles le cont\u00f3 su verg\u00fcenza.<br \/>- Si solo queda eso, no te preocupes, se har\u00e1 r\u00e1pido.<\/p>\n<p>Entonces el rey llam\u00f3 a sus s\u00fabditos, e inmediatamente llegaron tantas hormigas por todos lados que toda el \u00e1rea del \u00e1tico se cubri\u00f3 con ellas. Les explic\u00f3 qu\u00e9 hacer. Y aqu\u00ed est\u00e1n todos trabajando. Cuando termin\u00f3, el Rey Hormiga le dijo a Charles:<\/p>\n<p>- Est\u00e1 hecho.<br \/>Charles le dio las gracias y se fue con todas sus hormigas.<br \/>Al atardecer, cuando lleg\u00f3 la princesa, encontr\u00f3 a Charles sentado y esper\u00e1ndola en silencio.<br \/>- \u00bfEst\u00e1 hecho el trabajo? ella pregunt\u00f3.<br \/>&quot;S\u00ed, princesa, est\u00e1 hecho&quot;, respondi\u00f3 Charles en voz baja.<br \/>- Veamos eso.<\/p>\n<p>Y examin\u00f3 todas las pilas. Tom\u00f3 un pu\u00f1ado de cada uno y lo examin\u00f3 de cerca. No encontr\u00f3 en ning\u00fan mont\u00f3n una semilla que fuera diferente y que estuviera fuera de lugar. Ella estaba bastante asombrada.<\/p>\n<p>- Est\u00e1 bien hecho, dijo ella; vamos a cenar ahora.<br \/>A la ma\u00f1ana siguiente, le orden\u00f3 a Charles que cortara toda una larga avenida de grandes robles, y le dio como herramientas un hacha de madera, una sierra para madera y cu\u00f1as. Todos los \u00e1rboles ten\u00edan que estar derribados al atardecer del mismo d\u00eda.<\/p>\n<p>Aqu\u00ed, de nuevo, nuestro hombre se siente muy avergonzado.<br \/>&#039;A menos que el Rey Le\u00f3n venga en mi ayuda&#039;, se dijo a s\u00ed mismo, &#039;esta vez nunca saldr\u00e9 del bosque. Y llam\u00f3 al rey de los leones.<br \/>- \u00a1Rey de los Leones, ven en mi ayuda, porque realmente lo necesito!<br \/>Y el rey de los leones lleg\u00f3 inmediatamente.<br \/>- \u00bfQu\u00e9 hay para tu servicio, Carlos, ahijado del rey de Francia? pregunt\u00f3.<br \/>Charles le cont\u00f3 su verg\u00fcenza.<\/p>\n<p>- \u00bfEs solo eso? Entonces no te preocupes, no tardar\u00e1s en hacerlo.<br \/>El rey lanz\u00f3 un rugido terrible e inmediatamente llegaron los leones a la avenida.<br \/>- Vamos ! Hijos m\u00edos, les dijo el rey, desarraigad y destrozad todos estos \u00e1rboles por m\u00ed, \u00a1y pronto!<\/p>\n<p>Y aqu\u00ed est\u00e1n inmediatamente para ponerse a trabajar, y trabajar, cada uno de sus mejores. Todo hab\u00eda terminado, antes del atardecer.<br \/>Cuando lleg\u00f3 la princesa, se asombr\u00f3 al ver todos los robles arrancados y despedazados, y Charles durmiendo o fingiendo dormir, acostado de espaldas.<\/p>\n<p>- \u00a1Ah! aqu\u00ed hay, por ejemplo, un hombre! se dice a s\u00ed misma.<br \/>Se acerc\u00f3 a Charles, muy gentilmente, de puntillas, y le dio dos besos. Charles se despert\u00f3.<br \/>- Ya veo, el trabajo est\u00e1 hecho, dijo la princesa.<br \/>- S\u00ed, princesa, el trabajo est\u00e1 hecho.<br \/>- Est\u00e1 bien. Vamos a cenar, porque debes tener hambre.<\/p>\n<p>A la ma\u00f1ana siguiente, le dijeron que bajara y nivelara una gran monta\u00f1a, mucho m\u00e1s alta que la monta\u00f1a de Br\u00e9. Le dieron una carretilla y una pala de madera, y el trabajo deb\u00eda completarse antes del atardecer.<br \/>Llegado al pie de la monta\u00f1a, Charles se qued\u00f3 all\u00ed mir\u00e1ndolo, y se dijo a s\u00ed mismo:<\/p>\n<p>- Como hacer esto ? Nunca llegar\u00e9 al final. Pero el rey de los halcones a\u00fan no me ha funcionado. Debo llamarlo; No tengo otra esperanza que en \u00e9l.<br \/>- \u00a1Rey de los halcones, ven en mi ayuda, porque realmente lo necesito!<br \/>Y al instante se le acerc\u00f3 el rey de los halcones.<\/p>\n<p>- \u00bfQu\u00e9 hay para tu servicio, Carlos, ahijado del rey de Francia? pregunt\u00f3.<br \/>- La Princesa de Tronkolaine me dijo que esta alta monta\u00f1a tendr\u00e1 que ser cortada y nivelada antes del atardecer y, si no me ayudas, realmente no s\u00e9 c\u00f3mo superarla.<br \/>- Si es solo eso, no te preocupes; se har\u00e1 antes del atardecer.<\/p>\n<p>Entonces el rey de los halcones lanz\u00f3 un grito espantoso, e inmediatamente vinieron los halcones, y en tal n\u00famero que la luz del sol se oscureci\u00f3.<br \/>- \u00bfQu\u00e9 hay que hacer, nuestro rey? ellos preguntaron.<br \/>- Transportar esta monta\u00f1a desde all\u00ed, de modo que en su lugar haya una llanura llana; y rapido, rapido, mi<br \/>\u00a1ni\u00f1os!<\/p>\n<p>Et les voil\u00e0 de d\u00e9chirer la montagne avec leurs griffes, et de transporter la terre dans la mer. Si bien que le travail \u00e9tait encore termin\u00e9, longtemps avant le coucher du soleil, et personne n&#039;e\u00fbt dit qu&#039;il y avait une montagne l\u00e0 , la ma\u00f1ana.<br \/>Cuando lleg\u00f3 la princesa, al atardecer, encontr\u00f3 a Charles durmiendo, debajo de un \u00e1rbol, y le dio dos besos m\u00e1s. Se despert\u00f3 inmediatamente y dijo:<\/p>\n<p>- Y bien ! Princesa, el trabajo est\u00e1 hecho; mira, no hay m\u00e1s monta\u00f1a. Ahora, espero que vengas conmigo al palacio del Rey de Francia.<br \/>- Con todo mi coraz\u00f3n, respondi\u00f3 ella, y v\u00e1monos de inmediato.<\/p>\n<p>Y caminaron hacia la orilla del mar, los botes de Charles todav\u00eda estaban all\u00ed. Se embarcaron en \u00e9l y llegaron sanos y salvos a Francia. En el camino, visitaron al anciano, quien le dijo a Charles:<\/p>\n<p>- Bueno, hijo m\u00edo, \u00bflo has logrado?<br \/>- \u00a1S\u00ed, abuelo, y la bendici\u00f3n de Dios sea contigo!<br \/>- Est\u00e1 bien. Ve ahora a buscar a tu padrino; Tus pruebas y tus problemas han terminado y ya no me necesitar\u00e1s.<\/p>\n<p>Cuando Carlos lleg\u00f3 al palacio del rey, acompa\u00f1ado por la princesa de Tronkolaine, todos se sorprendieron al ver lo hermosa que era. El viejo rey perdi\u00f3 la cabeza y quiso casarse con ella de inmediato, aunque la reina, su esposa, a\u00fan no estaba muerta.<\/p>\n<p>- No, le dijo la Princesa, yo no vine aqu\u00ed para casarme contigo, ni el diablo que est\u00e1 aqu\u00ed contigo.<br \/>- \u00a1Un diablo aqu\u00ed! \u00bfD\u00f3nde est\u00e1? grit\u00f3 el rey.<br \/>&quot;El que tomas por tu ahijado es un demonio, y aqu\u00ed est\u00e1 tu verdadero ahijado&quot;, dijo, se\u00f1alando a Charles; este ha tenido todos los problemas, y la recompensa le corresponde a \u00e9l, y ser\u00e1 mi marido.<br \/>- \u00bfPero c\u00f3mo despides al diablo? pregunt\u00f3 el rey.<\/p>\n<p>- Busque primero a una mujer joven reci\u00e9n casada y con su primer hijo. Cuando lo encuentres, calienta un horno blanco y arroja al diablo en \u00e9l. Se revolcar\u00e1 y aullar\u00e1 de rabia, y har\u00e1 todo lo posible por salir del horno; pero la joven lo mantendr\u00e1 all\u00ed mostr\u00e1ndole su anillo de bodas.<\/p>\n<p>Se encontr\u00f3 a una mujer joven que llevaba a su primer hijo; calentaron un horno blanco y luego arrojaron al diablo en \u00e9l. Este luch\u00f3 y lanz\u00f3 terribles gritos, y todo el palacio tembl\u00f3. Pero, cuando intent\u00f3 salir del fuego, la joven le present\u00f3 su anillo en la boca del horno y lo hizo retroceder. Entonces dijo entonces:<\/p>\n<p>\u201cSi me hubiera quedado aqu\u00ed un a\u00f1o m\u00e1s, habr\u00eda reducido el reino a un estado desesperado.<\/p>\n<p>Pero ten\u00eda que morir all\u00ed.<\/p>\n<p>Entonces Charles estaba casado con la princesa de Tronkolaine. El viejo carbonero, su esposa y todos sus hijos tambi\u00e9n estaban en la boda. - \u00a1Aqu\u00ed es donde hubo una fiesta, entonces! \u00a1Y un estruendo y un estruendo y un bombardeo eterno! \u00a1Las campanas sonando a todo volumen, el gran estandarte de pie y los violines al frente!<\/p>\n<p><\/p>\t\t\t\t\t\t\t\t<\/div>\n\t\t\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/div>\n\t\t\t\t\t<\/div>\n\t\t<\/section>\n\t\t\t\t<\/div>","protected":false},"excerpt":{"rendered":"<p>Breton Mythology Wiki Esta es la historia de la Princesa de Tronkolaine. Hab\u00eda una vez un viejo carbonero que ten\u00eda... <\/p>","protected":false},"author":1,"featured_media":0,"parent":96,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-613","page","type-page","status-publish","hentry"],"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/mythslegendes.com\/es\/wp-json\/wp\/v2\/pages\/613","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/mythslegendes.com\/es\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"https:\/\/mythslegendes.com\/es\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"https:\/\/mythslegendes.com\/es\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/mythslegendes.com\/es\/wp-json\/wp\/v2\/comments?post=613"}],"version-history":[{"count":1,"href":"https:\/\/mythslegendes.com\/es\/wp-json\/wp\/v2\/pages\/613\/revisions"}],"predecessor-version":[{"id":24558,"href":"https:\/\/mythslegendes.com\/es\/wp-json\/wp\/v2\/pages\/613\/revisions\/24558"}],"up":[{"embeddable":true,"href":"https:\/\/mythslegendes.com\/es\/wp-json\/wp\/v2\/pages\/96"}],"wp:attachment":[{"href":"https:\/\/mythslegendes.com\/es\/wp-json\/wp\/v2\/media?parent=613"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}